{"id":1148,"date":"2024-03-10T19:27:50","date_gmt":"2024-03-10T18:27:50","guid":{"rendered":"https:\/\/www.jesusserranofrances.com\/?post_type=obra&#038;p=1148"},"modified":"2024-04-23T19:28:20","modified_gmt":"2024-04-23T17:28:20","slug":"rostros-de-la-guerra-no7","status":"publish","type":"rostros-de-la-guerra","link":"https:\/\/www.jesusserranofrances.com\/es\/rostros-de-la-guerra\/rostros-de-la-guerra-no7\/","title":{"rendered":"Rostros de la guerra N\u00ba7"},"content":{"rendered":"<ul class=\"uk-list\">\n<li>T\u00e9cnica mixta sobre madera<\/li>\n<li>45&#215;45 cm<\/li>\n<li>2005<\/li>\n<\/ul>\n","protected":false},"featured_media":1246,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/www.jesusserranofrances.com\/es\/wp-json\/wp\/v2\/rostros-de-la-guerra\/1148"}],"collection":[{"href":"https:\/\/www.jesusserranofrances.com\/es\/wp-json\/wp\/v2\/rostros-de-la-guerra"}],"about":[{"href":"https:\/\/www.jesusserranofrances.com\/es\/wp-json\/wp\/v2\/types\/rostros-de-la-guerra"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jesusserranofrances.com\/es\/wp-json\/wp\/v2\/media\/1246"}],"wp:attachment":[{"href":"https:\/\/www.jesusserranofrances.com\/es\/wp-json\/wp\/v2\/media?parent=1148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}